{"id":1986,"date":"2010-07-26T22:48:16","date_gmt":"2010-07-27T03:18:16","guid":{"rendered":"https:\/\/skatox.com\/blog\/?p=1986"},"modified":"2010-10-15T18:12:35","modified_gmt":"2010-10-15T22:42:35","slug":"robot-de-lego-resuelve-cubo-de-rubik-3%c3%973-usando-un-telefono-con-android","status":"publish","type":"post","link":"https:\/\/skatox.com\/blog\/2010\/07\/26\/robot-de-lego-resuelve-cubo-de-rubik-3%c3%973-usando-un-telefono-con-android\/","title":{"rendered":"Robot de Lego resuelve cubo de Rubik (3\u00d73) usando un telefono con Android"},"content":{"rendered":"<p>Hace unos meses publiqu\u00e9 un video de como un robot resolv\u00eda un cubo (4&#215;4) utilizando un N95, pues hoy encontr\u00e9 uno resolviendo un cubo 3&#215;3 pero utilizando un tel\u00e9fono con Android (creo que es un Motorola Droid\/Milestone) como publicidad del poder que tienen los chips <a href=\"https:\/\/es.wikipedia.org\/wiki\/ARM\" target=\"_blank\">ARM<\/a> utilizados en muchos dispositivos port\u00e1tiles hoy en d\u00eda.<\/p>\n<p style=\"text-align: center;\"><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><div class=\"lyte-wrapper\" title=\"The Amazing ARM Powered Android Speedcuber\" style=\"width:640px;max-width:100%;margin:5px auto;\"><div class=\"lyMe qsa_\\&amp;showinfo\\=1\" id=\"WYL_ylFb4pqAUd8\" itemprop=\"video\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><div><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/skatox.com\/blog\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FylFb4pqAUd8%2Fhqdefault.jpg\" \/><meta itemprop=\"embedURL\" content=\"https:\/\/www.youtube.com\/embed\/ylFb4pqAUd8\" \/><meta itemprop=\"duration\" content=\"PT1M38S\" \/><meta itemprop=\"uploadDate\" content=\"2010-05-14T15:33:13Z\" \/><\/div><div id=\"lyte_ylFb4pqAUd8\" data-src=\"https:\/\/skatox.com\/blog\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FylFb4pqAUd8%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC hidden\"><div class=\"tT\" itemprop=\"name\">The Amazing ARM Powered Android Speedcuber<\/div><\/div><button tabindex=\"0\" class=\"play\"><\/button><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/ylFb4pqAUd8\" rel=\"nofollow\"><img decoding=\"async\" src=\"https:\/\/skatox.com\/blog\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FylFb4pqAUd8%2F0.jpg\" alt=\"The Amazing ARM Powered Android Speedcuber\" width=\"640\" height=\"340\" \/><br \/>Ver este v\u00eddeo en YouTube<\/a><\/noscript><meta itemprop=\"description\" content=\"This is the latest and fastest cube solving robot demo from ARM. The smartphone solves the puzzle and instructs the &#039;bot how to move the pieces.\"><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:640px;margin:5px auto;\"><\/div><\/span><\/p>\n<p>Tal vez no impresione tanto como el pasado, pero siempre vale la pena verlo, sobretodo por el logo de Android bailando en la esquina superior derecha.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace unos meses publiqu\u00e9 un video de como un robot resolv\u00eda un cubo (4&#215;4) utilizando un N95, pues hoy encontr\u00e9 uno resolviendo un cubo 3&#215;3&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/skatox.com\/blog\/2010\/07\/26\/robot-de-lego-resuelve-cubo-de-rubik-3%c3%973-usando-un-telefono-con-android\/\">Seguir leyendo<span class=\"screen-reader-text\">Robot de Lego resuelve cubo de Rubik (3\u00d73) usando un telefono con Android<\/span><\/a><\/div>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[682,557,582,401],"tags":[683,684,685,950],"class_list":["post-1986","post","type-post","status-publish","format-standard","hentry","category-android","category-otras-cosas","category-planetas-linux","category-rubik","tag-android-2","tag-arm","tag-motorola","tag-rubik","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Robot de Lego resuelve cubo de Rubik (3\u00d73) usando un telefono con Android - El blog de Skatox<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skatox.com\/blog\/2010\/07\/26\/robot-de-lego-resuelve-cubo-de-rubik-3\u00d73-usando-un-telefono-con-android\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Robot de Lego resuelve cubo de Rubik (3\u00d73) usando un telefono con Android - El blog de Skatox\" \/>\n<meta property=\"og:description\" content=\"Hace unos meses publiqu\u00e9 un video de como un robot resolv\u00eda un cubo (4&#215;4) utilizando un N95, pues hoy encontr\u00e9 uno resolviendo un cubo 3&#215;3&#8230;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skatox.com\/blog\/2010\/07\/26\/robot-de-lego-resuelve-cubo-de-rubik-3\u00d73-usando-un-telefono-con-android\/\" \/>\n<meta property=\"og:site_name\" content=\"El blog de Skatox\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElWeblogdeSkatox\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-27T03:18:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2010-10-15T22:42:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skatox.com\/blog\/images\/2015\/12\/skatux.png\" \/>\n\t<meta property=\"og:image:width\" content=\"625\" \/>\n\t<meta property=\"og:image:height\" content=\"603\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Miguel Useche\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@skatox\" \/>\n<meta name=\"twitter:site\" content=\"@skatox\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Miguel Useche\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/skatox.com\\\/blog\\\/2010\\\/07\\\/26\\\/robot-de-lego-resuelve-cubo-de-rubik-3%c3%973-usando-un-telefono-con-android\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skatox.com\\\/blog\\\/2010\\\/07\\\/26\\\/robot-de-lego-resuelve-cubo-de-rubik-3%c3%973-usando-un-telefono-con-android\\\/\"},\"author\":{\"name\":\"Miguel Useche\",\"@id\":\"https:\\\/\\\/skatox.com\\\/blog\\\/#\\\/schema\\\/person\\\/e081bf33c5b0f1b0514e253cb578e1ba\"},\"headline\":\"Robot de Lego resuelve cubo de Rubik (3\u00d73) usando un telefono con Android\",\"datePublished\":\"2010-07-27T03:18:16+00:00\",\"dateModified\":\"2010-10-15T22:42:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/skatox.com\\\/blog\\\/2010\\\/07\\\/26\\\/robot-de-lego-resuelve-cubo-de-rubik-3%c3%973-usando-un-telefono-con-android\\\/\"},\"wordCount\":105,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/skatox.com\\\/blog\\\/#organization\"},\"keywords\":[\"android\",\"arm\",\"motorola\",\"Rubik\"],\"articleSection\":[\"Android\",\"Otras cosas\",\"Planetas\",\"Rubik\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/skatox.com\\\/blog\\\/2010\\\/07\\\/26\\\/robot-de-lego-resuelve-cubo-de-rubik-3%c3%973-usando-un-telefono-con-android\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/skatox.com\\\/blog\\\/2010\\\/07\\\/26\\\/robot-de-lego-resuelve-cubo-de-rubik-3%c3%973-usando-un-telefono-con-android\\\/\",\"url\":\"https:\\\/\\\/skatox.com\\\/blog\\\/2010\\\/07\\\/26\\\/robot-de-lego-resuelve-cubo-de-rubik-3%c3%973-usando-un-telefono-con-android\\\/\",\"name\":\"Robot de Lego resuelve cubo de Rubik (3\u00d73) usando un telefono con Android - El blog de Skatox\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skatox.com\\\/blog\\\/#website\"},\"datePublished\":\"2010-07-27T03:18:16+00:00\",\"dateModified\":\"2010-10-15T22:42:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/skatox.com\\\/blog\\\/2010\\\/07\\\/26\\\/robot-de-lego-resuelve-cubo-de-rubik-3%c3%973-usando-un-telefono-con-android\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/skatox.com\\\/blog\\\/2010\\\/07\\\/26\\\/robot-de-lego-resuelve-cubo-de-rubik-3%c3%973-usando-un-telefono-con-android\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/skatox.com\\\/blog\\\/2010\\\/07\\\/26\\\/robot-de-lego-resuelve-cubo-de-rubik-3%c3%973-usando-un-telefono-con-android\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/skatox.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Robot de Lego resuelve cubo de Rubik (3\u00d73) usando un telefono con Android\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/skatox.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/skatox.com\\\/blog\\\/\",\"name\":\"El blog de Skatox\",\"description\":\"Compartiendo mis opiniones inform\u00e1ticas mas all\u00e1 de los 280 caracteres\",\"publisher\":{\"@id\":\"https:\\\/\\\/skatox.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/skatox.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/skatox.com\\\/blog\\\/#organization\",\"name\":\"El blog de Skatox\",\"url\":\"https:\\\/\\\/skatox.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/skatox.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/skatox.com\\\/blog\\\/images\\\/2022\\\/03\\\/tux.png\",\"contentUrl\":\"https:\\\/\\\/skatox.com\\\/blog\\\/images\\\/2022\\\/03\\\/tux.png\",\"width\":218,\"height\":218,\"caption\":\"El blog de Skatox\"},\"image\":{\"@id\":\"https:\\\/\\\/skatox.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElWeblogdeSkatox\\\/\",\"https:\\\/\\\/x.com\\\/skatox\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/skatox\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MiguelAngelUsecheCastro\",\"https:\\\/\\\/x.com\\\/skatox\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/skatox.com\\\/blog\\\/#\\\/schema\\\/person\\\/e081bf33c5b0f1b0514e253cb578e1ba\",\"name\":\"Miguel Useche\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/skatox.com\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/aec95b02408138cb9d08288435373552.jpg?ver=1787883229\",\"url\":\"https:\\\/\\\/skatox.com\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/aec95b02408138cb9d08288435373552.jpg?ver=1787883229\",\"contentUrl\":\"https:\\\/\\\/skatox.com\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/aec95b02408138cb9d08288435373552.jpg?ver=1787883229\",\"caption\":\"Miguel Useche\"},\"sameAs\":[\"https:\\\/\\\/skatox.com\",\"https:\\\/\\\/x.com\\\/skatox\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Robot de Lego resuelve cubo de Rubik (3\u00d73) usando un telefono con Android - El blog de Skatox","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skatox.com\/blog\/2010\/07\/26\/robot-de-lego-resuelve-cubo-de-rubik-3\u00d73-usando-un-telefono-con-android\/","og_locale":"es_ES","og_type":"article","og_title":"Robot de Lego resuelve cubo de Rubik (3\u00d73) usando un telefono con Android - El blog de Skatox","og_description":"Hace unos meses publiqu\u00e9 un video de como un robot resolv\u00eda un cubo (4&#215;4) utilizando un N95, pues hoy encontr\u00e9 uno resolviendo un cubo 3&#215;3&#8230;","og_url":"https:\/\/skatox.com\/blog\/2010\/07\/26\/robot-de-lego-resuelve-cubo-de-rubik-3\u00d73-usando-un-telefono-con-android\/","og_site_name":"El blog de Skatox","article_publisher":"https:\/\/www.facebook.com\/ElWeblogdeSkatox\/","article_published_time":"2010-07-27T03:18:16+00:00","article_modified_time":"2010-10-15T22:42:35+00:00","og_image":[{"width":625,"height":603,"url":"https:\/\/skatox.com\/blog\/images\/2015\/12\/skatux.png","type":"image\/png"}],"author":"Miguel Useche","twitter_card":"summary_large_image","twitter_creator":"@skatox","twitter_site":"@skatox","twitter_misc":{"Escrito por":"Miguel Useche"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/skatox.com\/blog\/2010\/07\/26\/robot-de-lego-resuelve-cubo-de-rubik-3%c3%973-usando-un-telefono-con-android\/#article","isPartOf":{"@id":"https:\/\/skatox.com\/blog\/2010\/07\/26\/robot-de-lego-resuelve-cubo-de-rubik-3%c3%973-usando-un-telefono-con-android\/"},"author":{"name":"Miguel Useche","@id":"https:\/\/skatox.com\/blog\/#\/schema\/person\/e081bf33c5b0f1b0514e253cb578e1ba"},"headline":"Robot de Lego resuelve cubo de Rubik (3\u00d73) usando un telefono con Android","datePublished":"2010-07-27T03:18:16+00:00","dateModified":"2010-10-15T22:42:35+00:00","mainEntityOfPage":{"@id":"https:\/\/skatox.com\/blog\/2010\/07\/26\/robot-de-lego-resuelve-cubo-de-rubik-3%c3%973-usando-un-telefono-con-android\/"},"wordCount":105,"commentCount":1,"publisher":{"@id":"https:\/\/skatox.com\/blog\/#organization"},"keywords":["android","arm","motorola","Rubik"],"articleSection":["Android","Otras cosas","Planetas","Rubik"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/skatox.com\/blog\/2010\/07\/26\/robot-de-lego-resuelve-cubo-de-rubik-3%c3%973-usando-un-telefono-con-android\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/skatox.com\/blog\/2010\/07\/26\/robot-de-lego-resuelve-cubo-de-rubik-3%c3%973-usando-un-telefono-con-android\/","url":"https:\/\/skatox.com\/blog\/2010\/07\/26\/robot-de-lego-resuelve-cubo-de-rubik-3%c3%973-usando-un-telefono-con-android\/","name":"Robot de Lego resuelve cubo de Rubik (3\u00d73) usando un telefono con Android - El blog de Skatox","isPartOf":{"@id":"https:\/\/skatox.com\/blog\/#website"},"datePublished":"2010-07-27T03:18:16+00:00","dateModified":"2010-10-15T22:42:35+00:00","breadcrumb":{"@id":"https:\/\/skatox.com\/blog\/2010\/07\/26\/robot-de-lego-resuelve-cubo-de-rubik-3%c3%973-usando-un-telefono-con-android\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skatox.com\/blog\/2010\/07\/26\/robot-de-lego-resuelve-cubo-de-rubik-3%c3%973-usando-un-telefono-con-android\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skatox.com\/blog\/2010\/07\/26\/robot-de-lego-resuelve-cubo-de-rubik-3%c3%973-usando-un-telefono-con-android\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/skatox.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Robot de Lego resuelve cubo de Rubik (3\u00d73) usando un telefono con Android"}]},{"@type":"WebSite","@id":"https:\/\/skatox.com\/blog\/#website","url":"https:\/\/skatox.com\/blog\/","name":"El blog de Skatox","description":"Compartiendo mis opiniones inform\u00e1ticas mas all\u00e1 de los 280 caracteres","publisher":{"@id":"https:\/\/skatox.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skatox.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/skatox.com\/blog\/#organization","name":"El blog de Skatox","url":"https:\/\/skatox.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/skatox.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/skatox.com\/blog\/images\/2022\/03\/tux.png","contentUrl":"https:\/\/skatox.com\/blog\/images\/2022\/03\/tux.png","width":218,"height":218,"caption":"El blog de Skatox"},"image":{"@id":"https:\/\/skatox.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElWeblogdeSkatox\/","https:\/\/x.com\/skatox","https:\/\/www.linkedin.com\/in\/skatox\/","https:\/\/www.youtube.com\/c\/MiguelAngelUsecheCastro","https:\/\/x.com\/skatox\/"]},{"@type":"Person","@id":"https:\/\/skatox.com\/blog\/#\/schema\/person\/e081bf33c5b0f1b0514e253cb578e1ba","name":"Miguel Useche","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/skatox.com\/blog\/wp-content\/litespeed\/avatar\/aec95b02408138cb9d08288435373552.jpg?ver=1787883229","url":"https:\/\/skatox.com\/blog\/wp-content\/litespeed\/avatar\/aec95b02408138cb9d08288435373552.jpg?ver=1787883229","contentUrl":"https:\/\/skatox.com\/blog\/wp-content\/litespeed\/avatar\/aec95b02408138cb9d08288435373552.jpg?ver=1787883229","caption":"Miguel Useche"},"sameAs":["https:\/\/skatox.com","https:\/\/x.com\/skatox"]}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":1743,"url":"https:\/\/skatox.com\/blog\/2010\/02\/06\/robot-de-lego-resuelve-cubo-de-rubik-4x4-usando-un-nokia-n95\/","url_meta":{"origin":1986,"position":0},"title":"Robot de Lego resuelve cubo de Rubik (4&#215;4) usando un Nokia N95","author":"Miguel Useche","date":"6 de febrero de 2010","format":false,"excerpt":"Interesante v\u00ed\u00addeo sobre como resolver cubo de rubik con nokia N95 y el kit de robot de Lego, lo que hicieron hicieron fue un robot que toma las fotos de cada cara del cubo, calcula una soluci\u00f3n a trav\u00e9s del celular\/m\u00f3vil y le env\u00ed\u00ada al robot los pasos a ejecutar\u2026","rel":"","context":"En \u00abOtras cosas\u00bb","block_context":{"text":"Otras cosas","link":"https:\/\/skatox.com\/blog\/category\/otras-cosas\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":442,"url":"https:\/\/skatox.com\/blog\/2008\/11\/09\/software-para-resolver-el-cubo-de-rubik\/","url_meta":{"origin":1986,"position":1},"title":"Software para resolver el cubo de Rubik","author":"Miguel Useche","date":"9 de noviembre de 2008","format":false,"excerpt":"Para los que me conocen en persona se han podido dar cuenta que he estado enviciado con speedrubik (resolver el cubo de rubik lo mas r\u00e1pido\u00a0 posible) y hace tiempo estaba buscando un programa que me dijera como resolver el cubo de rubik en muy pocos pasos y as\u00ed\u00ad aprender\u2026","rel":"","context":"En \u00abRubik\u00bb","block_context":{"text":"Rubik","link":"https:\/\/skatox.com\/blog\/category\/otras-cosas\/rubik\/"},"img":{"alt_text":"Webcam escaneado el cubo de rubik","src":"https:\/\/i0.wp.com\/skatox.com\/blog\/images\/2008\/11\/webcam_software.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3102,"url":"https:\/\/skatox.com\/blog\/2014\/10\/22\/hacker-modifica-el-codigo-de-firefox-os-realiza-interesantes-experimentos\/","url_meta":{"origin":1986,"position":2},"title":"Hacker modifica el c\u00f3digo de Firefox OS y realiza interesantes experimentos","author":"Miguel Useche","date":"22 de octubre de 2014","format":false,"excerpt":"Jan Jongboom hizo una grandiosa ponencia en el pasado JsConf sobre Firefox OS, en ella explica que quer\u00eda comprar una Rasberry Pi para realizar experimentos y desarrollar programas, aunque el precio del dispositivo es atractivo, observ\u00f3 que un tel\u00e9fono Firefox OS de USD $25 ofrece casi lo mismo pero con\u2026","rel":"","context":"En \u00abFirefox OS\u00bb","block_context":{"text":"Firefox OS","link":"https:\/\/skatox.com\/blog\/category\/firefox\/firefox-os\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/Uy062kp-LM4\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2050,"url":"https:\/\/skatox.com\/blog\/2010\/11\/24\/consejos-para-mejorar-la-duracion-de-la-bateria-en-tu-telefono-con-android\/","url_meta":{"origin":1986,"position":3},"title":"Consejos para mejorar la duraci\u00f3n de la bater\u00eda en tu tel\u00e9fono con Android","author":"Miguel Useche","date":"24 de noviembre de 2010","format":false,"excerpt":"Mucha gente se queja \u00faltimamente de la duraci\u00f3n de la bater\u00eda en los tel\u00e9fonos, pero todos los dispositivos m\u00f3viles han cambiado mucho, hoy en d\u00eda los tel\u00e9fonos en Venezuela (y en todo el mundo) no tienen nada que ver con los que ten\u00edamos hace solo dos o tres a\u00f1os, hace\u2026","rel":"","context":"En \u00abAndroid\u00bb","block_context":{"text":"Android","link":"https:\/\/skatox.com\/blog\/category\/google\/android\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2356,"url":"https:\/\/skatox.com\/blog\/2012\/11\/16\/por-que-usar-cyanogenmod-en-mi-telefono-android\/","url_meta":{"origin":1986,"position":4},"title":"\u00bfPor qu\u00e9 usar Cyanogenmod en mi tel\u00e9fono Android?","author":"Miguel Useche","date":"16 de noviembre de 2012","format":false,"excerpt":"Ya a estas alturas todos deber\u00edamos conocer sobre Android, en mi opini\u00f3n, su popularidad ha sido gracias a su licencia abierta pues permite tanto a empresas como a la comunidad realizar modificaciones al sistema operativo para: adaptarlo a ciertos sectores del mercado, diferenciarse de otras compa\u00f1\u00edas inversoras en esta tecnolog\u00eda,\u2026","rel":"","context":"En \u00abAndroid\u00bb","block_context":{"text":"Android","link":"https:\/\/skatox.com\/blog\/category\/google\/android\/"},"img":{"alt_text":"Mi pantalla principal de Android","src":"https:\/\/i0.wp.com\/skatox.com\/blog\/images\/2012\/11\/2012-11-16-14.52.47-150x150.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":420,"url":"https:\/\/skatox.com\/blog\/2008\/10\/22\/felices-10-anos-netbeans\/","url_meta":{"origin":1986,"position":5},"title":"\u00a1Felices 10 a\u00f1os Netbeans!","author":"Miguel Useche","date":"22 de octubre de 2008","format":false,"excerpt":"Hoy est\u00e1 cumpliendo 10 a\u00f1os desde que sali\u00f3 a la luz Netbeans, en la p\u00e1gina oficial del evento podremos ver mucha informaci\u00f3n interesante si son usuarios de este excelente IDE (ya s\u00e9 que existe Eclipse pero no me gusta), les recomiendo que observen la parte de la historia de su\u2026","rel":"","context":"En \u00abNetbeans\u00bb","block_context":{"text":"Netbeans","link":"https:\/\/skatox.com\/blog\/category\/todo-lo-relacionado-al-desarrollo-de-software\/netbeans-2\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/skatox.com\/blog\/wp-json\/wp\/v2\/posts\/1986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skatox.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skatox.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skatox.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skatox.com\/blog\/wp-json\/wp\/v2\/comments?post=1986"}],"version-history":[{"count":0,"href":"https:\/\/skatox.com\/blog\/wp-json\/wp\/v2\/posts\/1986\/revisions"}],"wp:attachment":[{"href":"https:\/\/skatox.com\/blog\/wp-json\/wp\/v2\/media?parent=1986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skatox.com\/blog\/wp-json\/wp\/v2\/categories?post=1986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skatox.com\/blog\/wp-json\/wp\/v2\/tags?post=1986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}